{"id":8655,"date":"2019-10-01T14:51:30","date_gmt":"2019-10-01T12:51:30","guid":{"rendered":"https:\/\/www.economiaediritto.it\/?p=8655"},"modified":"2020-10-26T10:22:31","modified_gmt":"2020-10-26T09:22:31","slug":"blockchain-in-italia-molti-progetti-ma-pochi-investimenti","status":"publish","type":"post","link":"https:\/\/www.economiaediritto.it\/en\/blockchain-in-italia-molti-progetti-ma-pochi-investimenti\/","title":{"rendered":"Blockchain in Italia: molti progetti ma pochi investimenti"},"content":{"rendered":"<p style=\"text-align: justify;\">La <em>Blockchain<\/em> (catena di blocchi) \u00e8 una tecnologia sempre pi\u00f9 discussa e fa parte della pi\u00f9 grande categoria di <em>Distributed Ledger<\/em> <em>Technologies<\/em>, i sistemi basati su un registro distributivo in cui tutti i nodi possiedono la stessa copia di un <em>database<\/em> che pu\u00f2 essere letto e modificato.<\/p>\n<p style=\"text-align: justify;\">Negli ultimi tre anni sono stati realizzati 579 progetti nel Mondo e 328 solo nel 2018 (+76% rispetto al 2017). l&#8217;Italia si posiziona al terzo posto nella classifica Europea per numero di iniziative che hanno coinvolto le imprese: sono 150 i progetti italiani.<\/p>\n<p style=\"text-align: justify;\">Le realt\u00e0 imprenditoriali che hanno dato inizio a sperimentazioni in materia equivalgono al 59%, invece i settori in cui ci sono stati investimenti relativi alla <em>Blockchain<\/em> sono:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Finanza 48%<\/li>\n<li>Pubbliche Amministrazioni 10%<\/li>\n<li>Operatori Logistici 8%<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">In questi settori la <em>Blockchain<\/em> viene utilizzata per pagamenti (24%), gestione documentale (24%) e tracciabilit\u00e0 della filiera (22%).<\/p>\n<p style=\"text-align: justify;\">Bisogna ricordare che solo il 24% delle imprese ha una conoscenza adeguata della tecnologia, il 31% non sa nemmeno di cosa si tratti, il 32% la considera una rivoluzione (in futuro), il 2% dei CIO (direttori informatici) la considera come priorit\u00e0 attuale.<\/p>\n<p style=\"text-align: justify;\">Ad oggi solo Grandi Aziende o <em>Startup<\/em> che vogliono raccogliere Capitale tramite <em>Crowdfunding<\/em> via ICO (scommettendo sulle criptovalute) stanno investendo in <em>Blockchain<\/em> o <em>Distributed Ledger<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Blockchain (catena di blocchi) \u00e8 una tecnologia sempre pi\u00f9 discussa e fa parte della pi\u00f9 grande categoria di Distributed Ledger Technologies, i sistemi basati su un registro distributivo in <\/p>\n","protected":false},"author":1377,"featured_media":8658,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[10,2398,5,2496,2394,2297,2399],"tags":[2395,2403,2397,2402,2396,2400,2401,1980,383,2376,2295],"class_list":{"0":"post-8655","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","6":"hentry","7":"category-rubriche-economiche","8":"category-industria-4-0","9":"category-fascicoli","10":"category-numero-di-ottobre-2019","11":"category-new-economy","12":"category-notizie","13":"category-tecnologia","14":"tag-blockchain","15":"tag-criptovaluta","17":"tag-direttori-informatici","18":"tag-distributed-ledger","19":"tag-grandi-azienda","20":"tag-imprenditoria","21":"tag-industria-4-0","22":"tag-investimenti","23":"tag-new-economy","24":"tag-startup"},"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["it","en","es"],"languages":{"it":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false},"es":{"title":false,"content":false,"excerpt":false}}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.economiaediritto.it\/wp-content\/uploads\/2019\/03\/blockchain-3438501_1280.jpg?fit=1280%2C768&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9CRXF-2fB","jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.economiaediritto.it\/en\/wp-json\/wp\/v2\/posts\/8655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.economiaediritto.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.economiaediritto.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.economiaediritto.it\/en\/wp-json\/wp\/v2\/users\/1377"}],"replies":[{"embeddable":true,"href":"https:\/\/www.economiaediritto.it\/en\/wp-json\/wp\/v2\/comments?post=8655"}],"version-history":[{"count":5,"href":"https:\/\/www.economiaediritto.it\/en\/wp-json\/wp\/v2\/posts\/8655\/revisions"}],"predecessor-version":[{"id":8660,"href":"https:\/\/www.economiaediritto.it\/en\/wp-json\/wp\/v2\/posts\/8655\/revisions\/8660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.economiaediritto.it\/en\/wp-json\/wp\/v2\/media\/8658"}],"wp:attachment":[{"href":"https:\/\/www.economiaediritto.it\/en\/wp-json\/wp\/v2\/media?parent=8655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.economiaediritto.it\/en\/wp-json\/wp\/v2\/categories?post=8655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.economiaediritto.it\/en\/wp-json\/wp\/v2\/tags?post=8655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}