{"id":4943,"date":"2014-04-01T00:16:07","date_gmt":"2014-03-31T22:16:07","guid":{"rendered":"http:\/\/www.economiaediritto.it\/?p=4943"},"modified":"2014-04-01T10:26:32","modified_gmt":"2014-04-01T08:26:32","slug":"la-deducibilita-dei-costi-black-list","status":"publish","type":"post","link":"https:\/\/www.economiaediritto.it\/es\/la-deducibilita-dei-costi-black-list\/","title":{"rendered":"La deducibilit\u00e0 dei costi black list"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>(di Massimiliano Sammarco)<\/strong><\/p>\n<p style=\"text-align: justify;\">L&#8217;art. 110, commi 10, 11 e 12 del D.P.R. n. 917\/1986, detta la disciplina sostanziale relativa ai costi sostenuti dalle imprese nazionali per gli acquisti effettuati da fornitori residenti in Paesi extra UE, aventi un regime fiscale privilegiato (cosiddetti paradisi fiscali).<\/p>\n<p style=\"text-align: justify;\">La disposizione prevede, nello specifico, che non sono ammessi in deduzione dal reddito d&#8217;impresa le spese e gli altri componenti negativi derivanti da operazioni intercorse con imprese residenti in Stati o territori diversi da quelli individuati nella lista di cui al decreto ministeriale emanato ai sensi dell&#8217;art. 168-bis del D.P.R. n. 917\/1986 (c.d. Black list).<\/p>\n<p style=\"text-align: justify;\">Per effetto della disposizione contenuta nell&#8217;art. 110, comma 10, del T.U.I.R., in linea di principio non sono deducibili, dal reddito d&#8217;impresa, i seguenti costi:<\/p>\n<ul>\n<li>spese relative a transazioni economiche e commerciali, (ovvero gli acquisti di beni e\/o servizi dal fornitore estero);<\/li>\n<li><span style=\"text-align: justify;\">ogni altro componente negativo di reddito (ad esempio le svalutazioni; le perdite su crediti; gli ammortamenti; gli interessi e altri oneri finanziari derivanti da transazioni aventi causa finanziaria, le minusvalenze su cespiti ammortizzabili).<\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">L&#8217;art. 110, comma 11, del D.P.R. n. 917\/1986, consente al contribuente di disapplicare il regime di indeducibilit\u00e0 sancito dal comma 10. Infatti, la disciplina dell&#8217;indeducibilit\u00e0 dei costi black list, non si rende applicabile quando le imprese residenti in Italia, ai sensi del successivo comma 11 dell&#8217;art. 110 del D.P.R. n. 917\/1986, forniscono la prova che \u00able imprese estere svolgono prevalentemente un&#8217;attivit\u00e0 commerciale effettiva, ovvero che le operazioni poste in essere rispondono ad un effettivo interesse economico e che le stesse hanno avuto concreta esecuzione\u00bb.<\/p>\n<p style=\"text-align: justify;\">Si tratta di esimenti tra loro alternative la cui dimostrazione pu\u00f2 essere fornita dal contribuente in sede di controllo, oppure, sempre secondo l\u2019Agenzia, in via preventiva, cio\u00e8 prima di porre in essere l\u2019operazione, inoltrando all\u2019Amministrazione finanziaria apposita istanza di interpello.<\/p>\n<p style=\"text-align: justify;\">L\u2019Agenzia delle entrate ha elencato, a titolo esemplificativo e non esaustivo, alcuni documenti idonei a dimostrare l\u2019effettiva attivit\u00e0 commerciale, quali il bilancio di esercizio, l\u2019atto costitutivo, un prospetto descrittivo dell\u2019attivit\u00e0 esercitata, i contratti di locazione degli immobili adibiti a sede degli uffici e dell\u2019attivit\u00e0, la copia delle fatture delle utenze elettriche e telefoniche relative agli uffici e agli altri immobili utilizzati, i contratti di lavoro dei dipendenti che indicano il luogo di prestazione dell\u2019attivit\u00e0 lavorativa e le mansioni svolte, i conti correnti bancari aperti presso istituti locali, estratti conto bancari che diano evidenza delle movimentazioni finanziarie relative alle attivit\u00e0 esercitate, copia dei contratti di assicurazione relativi ai dipendenti e agli uffici, autorizzazioni sanitarie e amministrative relative all\u2019attivit\u00e0 e all\u2019uso dei locali. L\u2019esperienza ha dimostrato come alcuni di questi documenti sono impossibili da ottenere, soprattutto dai fornitori esteri appartenenti a gruppi multinazionali, in quanto a volte contengono delle informazioni riservate. Malgrado sia ragionevole sostenere questo, potrebbe succedere che i verificatori ritengano non provata la relativa esimente in quanto la societ\u00e0 non ha fornito la documentazione sopracitata, ma documentazione diversa, anche se sostanzialmente equipollente.<\/p>\n<p style=\"text-align: justify;\">In merito, all\u2019esimente dell\u2019interesse economico, si evidenzia come l\u2019Agenzia delle entrate ritiene necessario un confronto comparativo tra il prezzo al quale \u00e8 stata conclusa l\u2019operazione e quello potenzialmente raggiungibile nel mercato italiano o in altri mercati a fiscalit\u00e0 ordinaria, mentre la giurisprudenza ha al contrario sostenuto che tale interesse pu\u00f2 derivare da un\u2019analisi della sussistenza dell\u2019effettivo interesse economico nell\u2019operazione in s\u00e9. Qualche volta infatti mancano operazioni comparabili, perch\u00e9 si tratta di royalties, di marchi, di provvigioni, e di altre prestazioni non fungibili, e quindi non confrontabili col prezzo praticato da terzi, che in genere sar\u00e0 addirittura mancante.<\/p>\n<p style=\"text-align: justify;\">Da quanto fino ad ora esposto, emerge chiaramente come la verifica in merito alla violazione o meno della normativa si debba basare sui fatti e una loro valutazione potrebbe essere soggetta a diverse interpretazioni da parte delle parti.<\/p>\n<p style=\"text-align: justify;\">Sta di fatto, per\u00f2, che nel caso in cui l\u2019operatore non riesca a documentare una delle esimenti previste dalla normativa, ma sia abbastanza chiaro che l\u2019operazione abbia un senso economico per la sua impresa, questo dovrebbe essere sufficiente per evitare l\u2019irrogazione delle sanzioni, anche quelle di carattere penale quando dovessero superarsi le soglie previste di punibilit\u00e0.<\/p>\n<p style=\"text-align: justify;\">In tale caso, infatti, la violazione della normativa, consistente nella mancata produzione della documentazione richiesta sarebbe sanzionata solamente con l\u2019indeducibilit\u00e0 del costo.<\/p>\n<p style=\"text-align: justify;\">L\u2019applicazione anche di una specifica sanzione risulterebbe alquanto eccessiva, dal momento che non verrebbe posto il dubbio in merito all\u2019inerenza del costo alla produzione del reddito, ma solamente non sarebbe considerata sufficiente la documentazione prodotta a giustificazione del suo sostenimento.<\/p>\n<p style=\"text-align: justify;\">E come gi\u00e0 esposto precedentemente, i motivi per cui la documentazione richiesta dalla norma possa essere ritenuta insufficiente possono essere molteplici.<\/p>\n<p style=\"text-align: justify;\">Si pensi, ad esempio, ad un operatore italiano che \u00e8 costretto ad acquistare ad un prezzo elevatissimo un determinato bene necessario alla propria produzione da un determinato fornitore residente in Paese a fiscalit\u00e0 privilegiata, il quale \u00e8 l\u2019unico produttore mondiale che permette di ottenere determinate performances, ma non ha nessuna intenzione di fornire documenti in merito alla sua attivit\u00e0.<\/p>\n<p style=\"text-align: justify;\">In tale caso, potrebbe essere eccepito in capo al soggetto nazionale di avere posto in essere un\u2019operazione economicamente ingiustificata, visto l\u2019elevato prezzo di acquisto, e di non avere dimostrato le esimenti richieste dalla normativa, se non quella che l\u2019operazione \u00e8 stata effettivamente posta in essere.<\/p>\n<p style=\"text-align: justify;\">A meno che non venga dimostrato che il soggetto italiano abbia ricevuto indietro una parte del maggiore prezzo pagato, la sanzione non dovrebbe essere irrogata.<\/p>\n<p style=\"text-align: justify;\">Per concludere, si ritiene che l\u2019indeducibilit\u00e0 del costo per quegli operatori che intrattengono rapporti con soggetti residenti in Paesi black list sia una sanzione eccessiva, nel caso in cui sia evidente che l\u2019operazione ha un senso economico, ma non si \u00e8 giunti a fornire la prova suddetta.<\/p>\n<p style=\"text-align: justify;\">Quanto detto ci costringe a fare una brevissima considerazione. fermo restando il doveroso impegno che l&#8217;amministrazione finanziaria deve manifestare nella lotta all&#8217;evasione fiscale, non si pu\u00f2 non considerare il tessuto sociale economico e politico in cui le nostre imprese operano; un sistema globalizzato in cui gli scambi commerciali non necessariamente avvengono tra imprese appartenenti allo stesso stato, ne tantomeno si pu\u00f2 obbligare un&#8217;impresa ad instaurare rapporti commerciali con imprese residenti in stati non aventi una fiscalit\u00e0 privilegiata (scelta per altro giustificata da ragioni economico\/imprenditoriali) ecco, proprio quest&#8217;ultimo aspetto (cio\u00e8 quello del &#8220;obbligo&#8221;), comporta una ulteriore riflessione: chiedere ad un&#8217;impresa di dimostrare che il rapporto commerciale con la societ\u00e0 black list non sia stato instaurato al solo scopo di evadere le imposte in italia (con relativo dispendio di costi e tempo), significa, a nostro avviso, &#8220;obbligare&#8221; un&#8217;impresa a scegliere la controparte commerciale esclusivamente in base alla residenza di quest&#8217;ultima, piuttosto che sulla base di una valutazione di convenienza economica; tutto ci\u00f2 al fine di evitare accertamenti fiscali per difendersi dai quali, dimostrare la buona fede rischia di diventare &#8220;diabolico&#8221;.<\/p>\n<p style=\"text-align: justify;\">Continuando, ad esempio, qualora una societ\u00e0 italiana volesse investire in latino-america, con headquarter in Uruguay, magari in JV con una societ\u00e0 spagnola, si verificherebbe la seguente situazione:<\/p>\n<p style=\"text-align: justify;\">Per la Spagna l&#8217;Uruguay non \u00e8 paradiso fiscale e i due paesi hanno ratificato la convenzione contro le doppie imposizioni; per l&#8217;Italia, invece, l&#8217;Uruguay \u00e8 un paradiso fiscale, il che comporterebbe tutte le conseguenze di cui sopra, a discapito della concorrenza delle nostre imprese a livello globale.<\/p>\n<p style=\"text-align: justify;\">Non basterebbe invertire l&#8217;onere della prova &#8230; ?<\/p>\n<p style=\"text-align: justify;\">(fonte: www.corriereinfromazione.it)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(di Massimiliano Sammarco) L&#8217;art. 110, commi 10, 11 e 12 del D.P.R. n. 917\/1986, detta la disciplina sostanziale relativa ai costi sostenuti dalle imprese nazionali per gli acquisti effettuati da <\/p>\n","protected":false},"author":1377,"featured_media":3751,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[714,12,5,831,1],"tags":[858,77,857,859,689],"class_list":["post-4943","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fisc-int","category-rubriche-interdisciplinari","category-fascicoli","category-numero-di-aprile-2014","category-news","tag-acquisti","tag-agenzia-delle-entrate","tag-dpr-91786","tag-paesi-extra-ue","tag-tuir"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"es","enabled_languages":["it","en","es"],"languages":{"it":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false},"es":{"title":false,"content":false,"excerpt":false}}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.economiaediritto.it\/wp-content\/uploads\/2014\/02\/finance-185165_640.jpg?fit=637%2C640&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9CRXF-1hJ","jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.economiaediritto.it\/es\/wp-json\/wp\/v2\/posts\/4943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.economiaediritto.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.economiaediritto.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.economiaediritto.it\/es\/wp-json\/wp\/v2\/users\/1377"}],"replies":[{"embeddable":true,"href":"https:\/\/www.economiaediritto.it\/es\/wp-json\/wp\/v2\/comments?post=4943"}],"version-history":[{"count":2,"href":"https:\/\/www.economiaediritto.it\/es\/wp-json\/wp\/v2\/posts\/4943\/revisions"}],"predecessor-version":[{"id":5011,"href":"https:\/\/www.economiaediritto.it\/es\/wp-json\/wp\/v2\/posts\/4943\/revisions\/5011"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.economiaediritto.it\/es\/wp-json\/wp\/v2\/media\/3751"}],"wp:attachment":[{"href":"https:\/\/www.economiaediritto.it\/es\/wp-json\/wp\/v2\/media?parent=4943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.economiaediritto.it\/es\/wp-json\/wp\/v2\/categories?post=4943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.economiaediritto.it\/es\/wp-json\/wp\/v2\/tags?post=4943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}