{"id":6870,"date":"2016-03-01T00:08:15","date_gmt":"2016-02-29T23:08:15","guid":{"rendered":"http:\/\/www.economiaediritto.it\/?p=6870"},"modified":"2016-03-01T00:08:15","modified_gmt":"2016-02-29T23:08:15","slug":"il-segmento-artisti-affermati-avant-garde-market-quinta-parte","status":"publish","type":"post","link":"https:\/\/www.economiaediritto.it\/es\/il-segmento-artisti-affermati-avant-garde-market-quinta-parte\/","title":{"rendered":"Il segmento artisti affermati (Avant-Garde Market) \u2013 quinta parte"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>(di Marco Guenzi)<\/strong><\/p>\n<p style=\"text-align: justify;\">Nella precedente disamina del mercato degli artisti affermati (<em>Avant-Garde Market<\/em>) mancano all\u2019appello alcuni importanti temi, che si intende affrontare nel presente articolo e nel prossimo: ci si riferisce a quelli che possono essere i fattori critici di successo di un artista e a come viene distribuito il surplus su questo mercato (si rimanda invece al prossimo numero la trattazione del problema, sempre pi\u00f9 attuale, dell\u2019autenticit\u00e0 delle opere d\u2019arte e delle possibili misure di politica economica che possono essere messe in atto nel settore).<\/p>\n<p style=\"text-align: justify;\"><strong>I fattori critici di successo degli artisti<\/strong><\/p>\n<p style=\"text-align: justify;\">Quali sono i fattori strategici per lo sviluppo della carriera di un artista fino ad arrivare ad un riconoscimento a livello nazionale ed internazionale? Questa questione risulta essere cruciale per tutti i soggetti del sistema: innanzitutto per gli artisti stessi (che risultano essere direttamente coinvolti); inoltre per le gallerie (che da questi traggono i loro profitti); poi per i collezionisti, i mercanti d\u2019arte e gli investitori istituzionali (che devono prendere le decisioni con un\u2019ottica d\u2019investimento); infine per i rappresentanti della cultura (che devono effettuare le loro scelte in termini di interesse artistico).<\/p>\n<p style=\"text-align: justify;\">Per analizzare il problema bisogna partire dalle considerazioni fatte trattando il segmento <em>Alternative<\/em><a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>. Si \u00e8 visto che il panorama degli artisti emergenti che approdano a questo mercato \u00e8 costituito in gran parte da artisti \u201cdi mercato\u201d, cio\u00e8 da coloro che sono espressione delle tendenze artistiche in atto. Le gallerie di scoperta infatti generalmente li prediligono in quanto essi producono un prodotto di sicuro e facile apprezzamento, conforme agli standard vigenti di natura estetica e di contenuto. Tali artisti rassicurano inoltre i galleristi di scoperta per un altro importante motivo: \u00e8 improbabile, per i motivi che si esporranno, che essi possano avanzare nella carriera, facendo venire meno quell\u2019azzardo morale di essere lasciati e quindi vedere persi i propri investimenti promozionali.<\/p>\n<p style=\"text-align: justify;\">Se il fatto che ci sia una folta rappresentanza di artisti ripetitivi \u00e8 in parte positivo, in quanto permette di abbassare il livello complessivo di rischio del <em>Mercato Alternative<\/em> e attrarre gli investimenti privati<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a>, tuttavia il meccanismo di scelta messo in opera dal sistema delle gallerie di scoperta di fatto finisce per operare un\u2019<em>adverse selection<\/em> che penalizza gli artisti d\u2019avanguardia (cio\u00e8 innovativi) e nel suo complesso lo sviluppo culturale<a href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a>.<\/p>\n<p style=\"text-align: justify;\">Gli artisti d\u2019avanguardia non vengono infatti presi in debita considerazione in quanto essi risultano essere spesso troppo rischiosi per le gallerie di scoperta, sia per la tipologia di prodotto offerto (non apprezzabile dalla stragrande maggioranza dei collezionisti), sia per il rischio insito nella progressione naturale della carriera che vede l\u2019abbandono della galleria di partenza. Purtroppo avere un prodotto di valore non gli assicura sempre l\u2019ingresso nel sistema dell\u2019arte.<\/p>\n<p style=\"text-align: justify;\">In questo settore \u00e8 pure marginale la rappresentanza della categoria degli artisti sensazionalisti, ma per una ragione del tutto diversa: per la natura stessa della loro arte. Per far clamore bisogna infatti per definizione differenziarsi notevolmente dalla massa e quindi soltanto pochi artisti riescono nell\u2019intento. Gli artisti sensazionalisti, sebbene comportino anch\u2019essi un alto <em>moral hazard<\/em> legato alla progressione di carriera, sono particolarmente apprezzati dai galleristi, in quanto offrono un prodotto facilmente riconoscibile e quindi vendibile.<\/p>\n<p style=\"text-align: justify;\">E\u2019 curioso notare che invece nel mercato <em>Avant-Garde<\/em> la composizione delle forze in campo si ribalta: gli artisti di mercato tendono a scomparire mentre prendono pi\u00f9 spazio gli artisti sensazionalisti e d\u2019avanguardia.<\/p>\n<p style=\"text-align: justify;\">Si analizzino ora le ragioni di questo profondo cambiamento. Si \u00e8 in precedenza messo in evidenza, facendo un\u2019analogia tra carriera degli artisti e un Gran Premio di automobilismo<a href=\"#_ftn4\" name=\"_ftnref4\">[4]<\/a>, che tra i fattori pi\u00f9 determinanti nella corsa verso l\u2019affermazione (tralasciando naturalmente l\u2019influenza della casualit\u00e0) si ritrovano da una parte l\u2019abilit\u00e0 del pilota, che corrisponde alla capacit\u00e0 della galleria di attuare una strategia di comunicazione in grado di dare visibilit\u00e0 all\u2019artista, e dall\u2019altra le caratteristiche tecniche dell\u2019autovettura, ovvero il talento naturale dell\u2019artista.<\/p>\n<p style=\"text-align: justify;\">L\u2019attuazione di una efficace strategia di comunicazione dipende direttamente dalla capacit\u00e0 della galleria (e in secondo piano dell\u2019artista) di districarsi nel complicato sistema dell\u2019arte, caratterizzato da tutta una serie di convenzioni e regole antropologiche, sociali ed economiche tacite e consuetudinarie<a href=\"#_ftn5\" name=\"_ftnref5\">[5]<\/a>. A tal fine l\u2019artista e la galleria devono cercare di costruire il \u201ccapitale relazionale\u201d, cio\u00e8 tutta una serie di conoscenze e contatti necessari a manovrare le leve del sistema<a href=\"#_ftn6\" name=\"_ftnref6\">[6]<\/a>.<\/p>\n<p style=\"text-align: justify;\">Da questo punto di vista le strategie promozionali messe in piedi dalle gallerie di scoperta sono deficitarie per il settore <em>Avant-Garde<\/em>, per il fatto che tali gallerie non hanno abbastanza appoggi. Un artista emergente che voglia affermarsi e progredire nella propria carriera si trova quindi spesso nella condizione di dover cambiare rappresentanza, accettando le proposte di collaborazioni da parte di gallerie pi\u00f9 influenti, quelle tradizionali e di <em>brand,<\/em> che hanno apprezzato il suo lavoro.<\/p>\n<p style=\"text-align: justify;\">Le gallerie tradizionali e di <em>brand<\/em> tuttavia sono molto attente a scegliere i loro artisti, poich\u00e9 queste scelte si rifletteranno direttamente sulla loro immagine. Esse tenderanno a selezionare solo profili che presentano prospettive di successo, ovvero quegli artisti che secondo loro sono pi\u00f9 talentuosi o riconoscibili. Da questo punto di vista gli artisti di mercato sono poco considerati, mentre ricevono maggiori attenzioni artisti di avanguardia e sensazionalisti.<\/p>\n<p style=\"text-align: justify;\">Naturalmente \u00e8 importante anche che sia l\u2019artista stesso a valutare l\u2019offerta della galleria: egli dovr\u00e0 verificare innanzitutto di condividere i valori e il <em>modus operandi<\/em> del gallerista. Gli artisti sensazionalisti si trovano naturalmente bene con galleristi con forte piglio imprenditoriale (strategici) che sono soliti seguire strategie di <em>pricing<\/em> e comunicazione pi\u00f9 aggressive (<em>time-driven strategy<\/em>) , mentre quelli d\u2019avanguardia meglio si incontrano con coloro che svolgono questa professione pi\u00f9 per passione (appassionati), che in genere attuano strategie promozionali e dei prezzi pi\u00f9 conservative (<em>demand-driven strategy<\/em>).<\/p>\n<p style=\"text-align: justify;\">Al di l\u00e0 di ogni considerazione di tipo strategico, a questo punto di carriera risulta determinante per l\u2019artista nella scelta di una controparte valutare l\u2019influenza che la galleria pu\u00f2 avere nel sistema. Da questo punto di vista \u00e8 facile farsi un\u2019idea vedendo se essa \u00e8 ammessa alle fiere pi\u00f9 rinomate, se ha in portafoglio artisti affermati che espongono alle biennali e nei maggiori musei, quali sono i suoi prezzi medi di vendita, se agli eventi da questa organizzati partecipano importanti collezionisti, esponenti della cultura e del mondo <em>glamour<\/em> pi\u00f9 in generale, se essa \u00e8 inserita negli albi dei <em>Who\u2019s Who <\/em>del mondo dell\u2019arte.<\/p>\n<p style=\"text-align: justify;\">Una volta iniziata la collaborazione con la nuova galleria, \u00e8 bene che l\u2019artista dedichi le sue energie soprattutto alla ricerca e alla produzione artistica, in modo da produrre opere che siano sempre innovative, lasciando al gallerista l\u2019aspetto della promozione.<\/p>\n<p style=\"text-align: justify;\">Una galleria che si rispetti, da parte sua, comincer\u00e0 ad prendere contatti con il mondo della cultura (curatori e direttori musei) e del mercato (collezionisti) affinch\u00e9 l\u2019opera dell\u2019artista venga sempre pi\u00f9 conosciuta ed apprezzata. Da questo punto di vista la partecipazione a fiere di importanza internazionale pu\u00f2 essere un buon palcoscenico per farsi conoscere, oltre naturalmente a rappresentare l\u2019occasione di entrare a far parte di qualche collezione di rilievo. L\u2019obbiettivo primario rimane comunque quello di essere visti da curatori che possono inserire l\u2019opera dell\u2019artista in rassegne importanti e nelle collezioni dei musei; cos\u00ec come il contatto con critici e giornalisti che scrivano delle recensioni sull\u2019artista e sulle mostre da lui fatte su riviste specializzate di rilievo.<\/p>\n<p style=\"text-align: justify;\">L\u2019obiettivo della strategia di marketing \u00e8 quello di focalizzare l\u2019attenzione sul lavoro (e la figura) dell\u2019artista, ormai riconoscibili dagli addetti ai lavori, in modo da renderli un punto di riferimento. Secondo Adler<a href=\"#_ftn7\" name=\"_ftnref7\">[7]<\/a> il fattore chiave del successo di un artista consiste nell\u2019innesco di esternalit\u00e0 di rete che facciano crescere in modo esponenziale la riconoscibilit\u00e0 dell\u2019artista in modo da sostenerne fortemente la crescita professionale. L\u2019economista sostiene che chi deve comprare un\u2019opera d\u2019arte (o pi\u00f9 in generale un prodotto culturale) tende a ripetere le proprie scelte di consumo. Questo perch\u00e9 il fruitore di beni culturali ha un\u2019utilit\u00e0 marginale crescente al consumo, perch\u00e9 pi\u00f9 si diventa intenditori di qualcosa pi\u00f9 lo si apprezza<a href=\"#_ftn8\" name=\"_ftnref8\">[8]<\/a>. Cos\u00ec il collezionista che comincia a comprare un artista, tende a ripetere le proprie scelte (come d\u2019altronde avviene al supermercato con i prodotti di marca). Ci\u00f2 comporta che egli finisca cos\u00ec per non considerare artisti pi\u00f9 bravi, di cui per\u00f2 non \u00e8 a conoscenza.<\/p>\n<p style=\"text-align: justify;\">Ma come viene la sua prima scelta? In un mercato contraddistinto da un forte grado di asimmetrie informative, e quindi grandi difficolt\u00e0 a individuare ci\u00f2 che realmente gli interessa, il collezionista, per limiti di tempo e di fiducia nelle proprie capacit\u00e0 di apprezzamento, tender\u00e0 a comprare un artista di cui ha sentito dire.<\/p>\n<p style=\"text-align: justify;\">Questo fenomeno spinge ad un forte processo selettivo secondo il quale solo chi riesce ad attrarre inizialmente su di s\u00e9 l\u2019informazione del mercato ha la possibilit\u00e0 di vedere riconosciuto il proprio lavoro, condensare la domanda, far crescere le quotazioni e quindi ottenere ancora maggiore eco, secondo una spirale al rialzo che porta ad un rapido successo<a href=\"#_ftn9\" name=\"_ftnref9\">[9]<\/a>. Secondo questo approccio la notoriet\u00e0 \u00e8 il fattore che maggiormente influenza la domanda di investimento in opere d\u2019arte (<em>art stock demand)<\/em> e gli artisti che hanno maggiori probabilit\u00e0 di successo risultano essere quelli sensazionalisti. La figura 1 mostra la rapida ascesa della loro carriera<a href=\"#_ftn10\" name=\"_ftnref10\">[10]<\/a>.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/i0.wp.com\/www.economiaediritto.it\/wp-content\/uploads\/2016\/02\/Figura27-1.jpg\"><img decoding=\"async\" data-attachment-id=\"6871\" data-permalink=\"https:\/\/www.economiaediritto.it\/es\/il-segmento-artisti-affermati-avant-garde-market-quinta-parte\/figura27-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.economiaediritto.it\/wp-content\/uploads\/2016\/02\/Figura27-1.jpg?fit=800%2C600&amp;ssl=1\" data-orig-size=\"800,600\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Figura27-1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.economiaediritto.it\/wp-content\/uploads\/2016\/02\/Figura27-1.jpg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.economiaediritto.it\/wp-content\/uploads\/2016\/02\/Figura27-1.jpg?fit=700%2C525&amp;ssl=1\" tabindex=\"0\" role=\"button\" class=\"alignleft size-full wp-image-6871\" src=\"https:\/\/i0.wp.com\/www.economiaediritto.it\/wp-content\/uploads\/2016\/02\/Figura27-1.jpg?resize=700%2C525\" alt=\"Figura27-1\" width=\"700\" height=\"525\" srcset=\"https:\/\/i0.wp.com\/www.economiaediritto.it\/wp-content\/uploads\/2016\/02\/Figura27-1.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.economiaediritto.it\/wp-content\/uploads\/2016\/02\/Figura27-1.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.economiaediritto.it\/wp-content\/uploads\/2016\/02\/Figura27-1.jpg?resize=600%2C450&amp;ssl=1 600w\" sizes=\"(max-width: 700px) 100vw, 700px\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Tuttavia la sola strategia di comunicazione non basta per entrare a pieno titolo nei circoli ristretti del mondo dell\u2019arte che conta ed ottenere un successo duraturo: essa deve essere unita alle capacit\u00e0 artistiche. La notoriet\u00e0 da sola infatti produce fuochi di paglia e il mondo dell\u2019arte e dello spettacolo sono pieni di questi casi (si veda l\u2019esempio dei <em>talent show<\/em> televisivi, che portano sul palcoscenico artisti che, spente le luci della ribalta, finiscono presto nel dimenticatoio; parimenti il mondo dell\u2019arte \u00e8 pieno di artisti che, grazie a generosi inviti, partecipano a biennali e poi scompaiono dalla scena artistica). Il talento, invece, permette di ottenere un consenso da parte della comunit\u00e0 artistica, che a sua volta serve a costruirsi una solida reputazione sul mercato.<\/p>\n<p style=\"text-align: justify;\">Quando si parla di talento spesso si pensa ad una qualit\u00e0 innata. In parte infatti \u00e8 cos\u00ec. Se si pensa ad esempio ai grandi campioni sportivi o a geni della musica, non si pu\u00f2 far altro che ammirare qualit\u00e0 tecniche che sembrano non richiedere alcuno sforzo: in realt\u00e0 quelle qualit\u00e0 si sono sviluppate attraverso un continuo esercizio, ripetuto cos\u00ec tante volte nel tempo da divenire un automatismo. Tale dedizione \u00e8 difficile che sia solo frutto della forza di volont\u00e0, dell\u2019auto-costrizione, ma \u00e8 probabile piuttosto che trovi nutrimento nel piacere di dedicarsi a ci\u00f2 che si fa. Si pu\u00f2 quindi dire che il talento deriva s\u00ec da una predisposizione dell\u2019individuo per una specifica attivit\u00e0, ma se quest\u2019ultima non diventa una passione, esso non verr\u00e0 mai scoperto (\u00e8 quindi frutto della fortunata combinazione di trovare qualcosa che ci si diverte a fare e che poi, forse proprio per questo motivo, si riuscir\u00e0 a fare meglio di altri, piuttosto che il contrario).<\/p>\n<p style=\"text-align: justify;\">Da questo punto di vista si ritiene che l\u2019obiettivo dell\u2019artista sia quello produrre opere d\u2019arte che siano sia innovative che espressive, in grado cio\u00e8 di lasciare a bocca aperta lo spettatore, ampliare l\u2019immaginario comune e di convogliare significati che permangano nel tempo, o come dice Sacco: \u201ccreare processi di senso\u201d<a href=\"#_ftn11\" name=\"_ftnref11\">[11]<\/a>.<\/p>\n<p style=\"text-align: justify;\">Secondo Rosen<a href=\"#_ftn12\" name=\"_ftnref12\">[12]<\/a> il successo e i guadagni delle <em>celebrities<\/em> dipendono dal fatto che i beni culturali sono imperfetti sostituti. Chi ha pi\u00f9 talento degli altri, offrendo a prezzi concorrenziali servizi culturali di maggior pregio (che potrebbero essere dischi, libri, film, spettacoli, o nella fattispecie mostre), tende a concentrare la domanda su di s\u00e9. Secondo tale teoria il talento viene fortemente ricercato e, attraverso il passaparola, agisce da cassa di risonanza, incrementando la domanda di <em>art service <\/em>e portando l\u2019artista al successo. Gli artisti che avranno il maggiori riconoscimenti dovranno quindi essere quelli d\u2019avanguardia: il loro cammino verso la consacrazione sar\u00e0 per\u00f2 pi\u00f9 graduale (si veda la figura 2)<a href=\"#_ftn13\" name=\"_ftnref13\">[13]<\/a>.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/i0.wp.com\/www.economiaediritto.it\/wp-content\/uploads\/2016\/02\/Figura27-2.jpg\"><img decoding=\"async\" data-attachment-id=\"6872\" data-permalink=\"https:\/\/www.economiaediritto.it\/es\/il-segmento-artisti-affermati-avant-garde-market-quinta-parte\/figura27-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.economiaediritto.it\/wp-content\/uploads\/2016\/02\/Figura27-2.jpg?fit=800%2C600&amp;ssl=1\" data-orig-size=\"800,600\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Figura27-2\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.economiaediritto.it\/wp-content\/uploads\/2016\/02\/Figura27-2.jpg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.economiaediritto.it\/wp-content\/uploads\/2016\/02\/Figura27-2.jpg?fit=700%2C525&amp;ssl=1\" tabindex=\"0\" role=\"button\" class=\"alignleft size-full wp-image-6872\" src=\"https:\/\/i0.wp.com\/www.economiaediritto.it\/wp-content\/uploads\/2016\/02\/Figura27-2.jpg?resize=700%2C525\" alt=\"Figura27-2\" width=\"700\" height=\"525\" srcset=\"https:\/\/i0.wp.com\/www.economiaediritto.it\/wp-content\/uploads\/2016\/02\/Figura27-2.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.economiaediritto.it\/wp-content\/uploads\/2016\/02\/Figura27-2.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.economiaediritto.it\/wp-content\/uploads\/2016\/02\/Figura27-2.jpg?resize=600%2C450&amp;ssl=1 600w\" sizes=\"(max-width: 700px) 100vw, 700px\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Il talento naturale serve quindi ad ottenere consenso e il consenso ad ottenere notoriet\u00e0, che a sua volta si riflette sui prezzi di mercato. Tuttavia questo meccanismo di trasmissione non \u00e8 cos\u00ec lineare a causa (tra le tante varianti) delle inefficienze del mercato.<\/p>\n<p style=\"text-align: justify;\">Il problema del mercato dell\u2019arte contemporanea \u00e8 che i consumatori di questo bene non sono sicuri dei loro giudizi di merito. Alcuni studi hanno rilevato che la maggior parte degli individui non si astengono dal commentare (esprimendo e motivando il proprio apprezzamento) su dischi, libri o film, ma solo pochissimi si azzardano ad abbozzare un giudizio articolato davanti ad un quadro, un\u2019installazione o un video<a href=\"#_ftn14\" name=\"_ftnref14\">[14]<\/a>. I consumatori di arte contemporanea nella stragrande maggioranza quindi necessitano nelle loro scelte di consumo di acquisire segnali di valore esterni in grado di confermare il proprio punto di vista (ovvero di fattori di rinforzo dell\u2019opinione).<\/p>\n<p style=\"text-align: justify;\">Tali fattori sono rappresentati dalle argomentazioni portate avanti da parte degli <em>opinion-makers<\/em>, tra cui i galleristi di un certo peso.<a href=\"#_ftn15\" name=\"_ftnref15\">[15]<\/a> Questi ultimi cercano di usare il loro potere d\u2019opinione per convincere i loro potenziali acquirenti ad investire sui loro artisti. A tal fine cercano di giustificare il valore del prezzo di vendita con elementi oggettivi (<em>sell out situations<\/em>): la partecipazione a biennali, l\u2019acquisizione delle opere da parte di musei o importanti collezionisti, il passaggio da una galleria di scoperta a una tradizionale con maggiori appoggi, la creazione di un mercato secondario e la quotazione ufficiale attraverso le attribuzioni all\u2019asta, la partecipazione con successo a premi di rilevanza nazionale e internazionale. Pu\u00f2 inoltre essere molto importante come fattore di rinforzo la creazione di una narrazione (<em>script<\/em>) intorno all\u2019opera e all\u2019artista: i collezionisti infatti amano prodigarsi in spiegazioni ed aneddoti che illustrino opere da loro acquistate, cos\u00ec da far sfoggio di raffinatezza, gusto e ampiezza di orizzonti culturali. Le opere con uno <em>script <\/em>si adattano inoltre bene alle collezioni museali: le narrazioni possono accompagnare ed arricchire le visite per mezzo di guide o audio-visivi.<\/p>\n<p style=\"text-align: justify;\">Ad uno stadio pi\u00f9 avanzato pu\u00f2 essere il giudizio stesso del gallerista ad essere sostituito a quello del collezionista, in una sorta di rapporto fiduciario in cui il primo ci mette la faccia e il secondo il portafoglio. Tali dinamiche vengono in genere ad instaurarsi nel Mercato <em>Avant-Garde<\/em> per le gallerie di <em>brand<\/em>, il cui nome da solo serve a rassicurare i compratori<a href=\"#_ftn16\" name=\"_ftnref16\">[16]<\/a>.<\/p>\n<p style=\"text-align: justify;\">Le strategie di marketing che le gallerie tendono a seguire tuttavia variano in funzione degli artisti rappresentati. Per gli artisti sensazionalisti esse fanno principalmente leva sul fattore clamore. Utilizzano infatti il fenomeno delle esternalit\u00e0 di rete, prodotte grazie ad una attenta strategia di comunicazione, in modo da far oltrepassare all\u2019artista un certo livello soglia di notoriet\u00e0. A quel punto il suo prodotto tende a diventare virale e le quotazioni crescono in maniera automatica. La comunit\u00e0 poi tende a vedere questi aspetti come fattori di rinforzo del talento degli artisti sensazionalisti, che spesso vengono successivamente anche considerati dalla critica, arrivando cos\u00ec ad una rapida affermazione.<\/p>\n<p style=\"text-align: justify;\">Gli artisti d\u2019avanguardia invece tendono a far valere il loro messaggio innovativo attraverso il canale culturale, ottenendo innanzitutto il sostegno da parte della comunit\u00e0 dei critici e dei curatori. Per essi la porta di entrata per raggiungere la soglia critica del successo non \u00e8 rappresentata da operazioni di marketing ma dalla possibilit\u00e0 di esporre in contesti di un certo livello. Il processo di progressione di carriera \u00e8 in questo caso molto pi\u00f9 lento, ma in genere pi\u00f9 solido.<\/p>\n<p style=\"text-align: justify;\"><strong>La distribuzione del surplus<\/strong><\/p>\n<p style=\"text-align: justify;\">A prescindere da come si sia arrivati al successo, si potrebbe dire che il valore aggiunto (cio\u00e8 il <em>surplus<\/em>) prodotto da un artista affermato \u00e8 sicuramente maggiore di quello creato da un artista emergente. Se ci\u00f2 \u00e8 vero nella grande maggioranza dei casi, tuttavia non \u00e8 sempre scontato. Un altro punto interessante \u00e8 vedere poi come viene distribuito il <em>surplus<\/em> tra i differenti <em>stake-holder<\/em> che operano sul mercato.<\/p>\n<p style=\"text-align: justify;\">Prima di affrontare queste questioni tuttavia \u00e8 necessario ricordare la distinzione tra capitale culturale, simbolico ed economico (il termine stesso di <em>surplus<\/em> infatti pu\u00f2 dare adito a diverse interpretazioni). Il primo indica il valore culturale del lavoro di un artista in riferimento alla storia dell\u2019arte (e quindi costituisce una variabile di lungo periodo). Il secondo viene definito da Bourdieu come il valore che le cose assumono per i soggetti in base alle loro percezioni e rappresentazioni<a href=\"#_ftn17\" name=\"_ftnref17\">[17]<\/a> (ed \u00e8 quindi variabile di medio periodo riferendosi ad una determinata congiuntura storica e culturale). Il terzo corrisponde al valore di mercato a cui un bene \u00e8 venduto. Da questo punto di vista<a href=\"#_ftn18\" name=\"_ftnref18\">[18]<\/a> il valore economico fa riferimento al prezzo di equilibrio di mercato di breve periodo, ottenuto dall\u2019incontro tra domanda (che a sua volta fa capo al valore simbolico) e offerta (che si confronta con i costi di produzione e commercializzazione), e influenzato nello stesso tempo da altri elementi (inefficienze) che assumono rilevanza sul mercato.<\/p>\n<p style=\"text-align: justify;\">Si pu\u00f2 quindi dire che il valore economico di un opera d\u2019arte nel medio periodo fa riferimento, oltre che ai costi sostenuti per la produzione e la promozione, al suo valore simbolico (che secondo Velthuis a sua volta dipende dal prezzo, secondo un meccanismo circolare)<a href=\"#_ftn19\" name=\"_ftnref19\">[19]<\/a>. Nel lungo periodo tuttavia il valore simbolico (e quindi il valore economico) tende a riflettere il valore culturale;<a href=\"#_ftn20\" name=\"_ftnref20\">[20]<\/a> nel breve periodo invece esso pu\u00f2 dipendere anche da fattori congiunturali (le inefficienze del mercato).<\/p>\n<p style=\"text-align: justify;\">Sulla base di queste considerazioni la distribuzione del <em>surplus<\/em> non va analizzata sulla base del prezzo di vendita, ma tenendo conto di quelle che sono le prospettive di crescita dell\u2019artista. Non solo: poich\u00e9 l\u2019acquisto di opere d\u2019arte costituisce un investimento, soggetto a fluttuazioni di valore economico (o in conto capitale), non va soltanto considerato il rendimento effettivo (<em>surplus<\/em>) ma anche il rendimento atteso in correlazione al livello di rischio annesso all\u2019investimento.<a href=\"#_ftn21\" name=\"_ftnref21\">[21]<\/a><\/p>\n<p style=\"text-align: justify;\">Si consideri a proposito che il mercato <em>Avant-Garde<\/em> \u00e8 molto selettivo e vede ridurre i contendenti secondo una legge logaritmica (questo vale d\u2019altronde anche per i segmenti inferiori). Ci\u00f2 significa che la stragrande maggioranza degli artisti che approdano a questo settore n\u00e9 arriveranno a quotazioni stratosferiche, n\u00e9 entreranno nei libri di storia dell\u2019arte. Per questi artisti il capitale simbolico e culturale \u00e8 gi\u00e0 stato convertito in toto in capitale economico e paradossalmente il surplus da essi prodotto \u00e8 minore di quello di artisti ai primi stadi della loro carriera che poi avranno un successo planetario.<\/p>\n<p style=\"text-align: justify;\">Per chi investe in questo settore quindi \u00e8 molto difficile determinare quali siano gli artisti eletti, destinati a diventare vere e proprie <em>celebrities<\/em>, pur trattandosi di una scelta che comprende soggetti che comunque hanno gi\u00e0 ottenuto un certo riconoscimento da parte del sistema dell\u2019arte.<\/p>\n<p style=\"text-align: justify;\">Inoltre vanno considerati due ulteriori fattori che fanno aumentare il rischio di investimento . Uno: il livello dei prezzi di acquisto \u00e8 gi\u00e0 molto rilevante e non permette ad investitori senza grandi risorse finanziarie una alta diversificazione del portafoglio. Due: una rilevante parte degli investitori su questo mercato, che ricordiamo non essere regolamentato, \u00e8 costituito da operatori che hanno una certa influenza nel sistema e che quindi sono in grado di influenzare fortemente a loro favore l\u2019andamento delle quotazioni degli artisti, a discapito di chi non ha il loro potere. Tale azione di controllo pu\u00f2 avvenire sia a livello di <em>opinion-making<\/em>, che in maniera pi\u00f9 scorretta (sebbene lecita) attraverso turbative di mercato.<a href=\"#_ftn22\" name=\"_ftnref22\">[22]<\/a><\/p>\n<p style=\"text-align: justify;\">Le possibilit\u00e0 di profitto per chi compra sul mercato <em>Avant-Garde<\/em> scemano poi ulteriormente nel caso egli decidesse di comprare sul mercato secondario all\u2019asta o dai mercanti d\u2019arte, i cui prezzi sono mediamente pi\u00f9 alti, mentre acquistando direttamente dalle gallerie, che applicano in genere un <em>mark-down<\/em>, si presentano maggiori possibilit\u00e0 di margine.<\/p>\n<p style=\"text-align: justify;\">Nel mercato <em>Avant-Garde<\/em> (come d\u2019altronde avviene per gli altri segmenti) il <em>surplus<\/em> relativo ad artisti che si trovano all\u2019apice della propria carriera viene interamente accaparrato dai venditori (artisti e gallerie, collezionisti, mercanti d\u2019arte e, in veste di intermediari, mediatori e case d\u2019asta). Va notato che la ripartizione degli utili tra artisti e gallerie tende tuttavia ad essere differente, e pi\u00f9 a favore dei primi rispetto al segmento <em>Alternative<\/em>. Ci\u00f2 in ragione del loro maggior potere contrattuale e dei margini molto elevati delle gallerie (le gallerie tradizionali sostengono in rapporto ai ricavi minori costi rispetto a quelle di scoperta, potendo sfruttare gli investimenti effettuati precedentemente da queste ultime), che sono quindi disposte a maggiori concessioni a favore degli artisti.<\/p>\n<p style=\"text-align: justify;\">Per quanto riguarda invece quei pochi artisti destinati ad ascendere al mercato <em>Classical Contemporary<\/em> (o <em>High End<\/em>) e quindi divenire celebrit\u00e0, tenendo conto delle quotazioni stratosferiche fori dalla norma che tali artisti riusciranno a raggiungere, il capitale simbolico e (talvolta)<a href=\"#_ftn23\" name=\"_ftnref23\">[23]<\/a> quello culturale non sono stati ancora convertiti in capitale economico. Fermo restando il <em>surplus<\/em> destinato al venditore, chi compra questi artisti ha quindi davanti grandissimi margini di profitto, almeno nel medio periodo: se egli sapr\u00e0 rivenderli al momento giusto, si pu\u00f2 dire che egli avr\u00e0 fatto<em> Bingo<\/em>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\">Note<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Cfr. Guenzi M. (2015), \u201cIl mercato degli artisti emergenti (<em>Alternative Market<\/em>) &#8211; quarta parte\u201d, <em>Economia e Diritto<\/em>, n. 10.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> Cellini R., Cuccia T. (2003), \u201cIncomplete Information and Experimentation in the Arts: A Game Theory Approach\u201d, <em>Economia Politica<\/em>, Il Mulino, Bologna, n.1 pp. 21-34.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> Guenzi M. (2014), \u201cAnomalie del mercato dell&#8217;arte contemporanea: il problema della selezione avversa degli artisti\u201d, <em>Economia e Diritto<\/em>, n. 11.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref4\" name=\"_ftn4\">[4]<\/a> Guenzi M. (2015), <em>Op. Cit<\/em>..<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref5\" name=\"_ftn5\">[5]<\/a> Da questo punto di vista il mercato dell\u2019arte pu\u00f2 essere definito il pi\u00f9 grande mercato mondiale non regolamentato di tipo lecito. Sarebbe naturalmente auspicabile una istituzione al suo interno di codici etici scritti e una regolamentazione per via legislativa che permetta di sanare gli evidenti conflitti di interessi che si vengono a creare nel suo interno, come invece avviene nei mercati finanziari. La mancata regolamentazione ha un impatto diretto sulla qualit\u00e0 dello sviluppo culturale, oltre naturalmente ad avere un risvolto economico, in quanto un mercato inefficiente produce minor <em>surplus<\/em>.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref6\" name=\"_ftn6\">[6]<\/a> Sacco P. (2005), \u201cLa selezione dei giovani artisti nei mercati delle arti visive\u201d, in Santagata W. (a cura di) (2005), <em>Economia dell\u2019arte. Istituzioni e mercati dell\u2019arte e della cultura<\/em>, Torino, Utet, pp. 42-75.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref7\" name=\"_ftn7\">[7]<\/a> Adler (1985), \u201cStardom and Talent\u201d, <em>American Economic Review<\/em>, Vol. 75, pp. 208-212.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref8\" name=\"_ftn8\">[8]<\/a> Cfr. anche Stigler G. \u2013 Becker G. (1977), \u201cDe Gustibus Non Est Disputandum\u201d, <em>American Economic Review<\/em>, Vol. 67, pp. 76-90.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref9\" name=\"_ftn9\">[9]<\/a> Si avr\u00e0 modo di vedere meglio questo aspetto quando si prender\u00e0 in esame il mercato <em>Classical Contemporary<\/em>.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref10\" name=\"_ftn10\">[10]<\/a> Nella figura 1 sono rappresentati due possibili andamenti della carriera degli artisti sensazionalistici: il caso di un successo immediato, quando gli artisti riescono nell\u2019intento di ottenere diffusione virale del proprio lavoro, e quello di un medio successo, quando ci\u00f2 non avviene.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref11\" name=\"_ftn11\">[11]<\/a> Sacco cos\u00ec spiega cosa intende per \u00abprocessi di senso\u00bb: \u201cLa qualit\u00e0 di un\u2019opera d\u2019arte visiva non dipende tanto da ci\u00f2 che essa mostra quanto piuttosto da ci\u00f2 che evoca, dove naturalmente il potenziale evocativo va misurato sulla base delle categorie mentali e della cultura condivisa della piccola <em>\u00e9lite<\/em> di specialisti che, secondo la pittoresca ma efficace espressione di Tom Wolfe, \u00abassegna le coppe ai vincitori\u00bb.\u201d (Sacco P. (2005), <em>Op. Cit<\/em>.).<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref12\" name=\"_ftn12\">[12]<\/a> Rosen (1981), \u201cThe Economics of Superstars\u201d, <em>American Economic Review<\/em>, Vol. 71, pp. 845-858.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref13\" name=\"_ftn13\">[13]<\/a> Nella figura 2 sono rappresentate le diverse vie che pu\u00f2 prendere la carriera di un artista d\u2019avanguardia: di successo graduale, di successo tardivo (in caso di riscoperta), di medio successo (a causa di un talento non eccezionale) e di insuccesso (a causa del fenomeno dell\u2019<em>adverse selection<\/em>).<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref14\" name=\"_ftn14\">[14]<\/a> Thompson D. (2014), <em>The Supermodel and the Brillo Box, Back Stories and Peculiar Economics from the World of Contemporary Art, <\/em>Palgrave MacMillian, New York.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref15\" name=\"_ftn15\">[15]<\/a> Tra i diversi <em>opinion-makers<\/em> \u00e8 possibile elencare, oltre ai maggiori galleristi, i grandi mercanti d\u2019arte e collezionisti, i direttori dei maggiori musei, i curatori di biennali e i critici riconosciuti a livello internazionale, che con la loro attivit\u00e0 supportano la creazione di valore aggiunto (<em>surplus<\/em>). Questi influenti individui hanno di fatto il potere di fare delle profezie che si auto-avverano (si pensi ad un curatore che stima un artista, vede per lui una possibile crescita di carriera, e quindi lo invita ad una biennale). Forse proprio per questo motivo sono cos\u00ec tenuti in considerazione dagli altri addetti ai lavori, che per\u00f2 in questa maniera, privandosi di una propria autonomia di opinione, aumentano ulteriormente l\u2019influenza di questi personaggi.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref16\" name=\"_ftn16\">[16]<\/a> Thompson D. (2014), <em>Op. Cit<\/em>..<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref17\" name=\"_ftn17\">[17]<\/a> Secondo Bourdieu: \u201c<em>J&#8217;appelle capital symbolique n&#8217;importe quelle esp\u00e8ce de capital (\u00e9conomique, culturel, scolaire ou social) lorsqu&#8217;elle est per\u00e7ue selon des cat\u00e9gories de perception, des principes de vision et de division, des syst\u00e8mes de classement, des sch\u00e8mes classificatoires, des sch\u00e8mes cognitifs, qui sont, au moins pour une part, le produit de l&#8217;incorporation des structures objectives du champ consid\u00e9r\u00e9, c-\u00e0-d de la structure de la distribution du capital dans le champ consid\u00e9r\u00e9.\u201d<\/em> (Bourdieu P. (1994), <em>Raisons Pratiques Sur la Th\u00e9orie de L&#8217;Action<\/em>, Seuil, Paris).<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref18\" name=\"_ftn18\">[18]<\/a> Si presenta qui un\u2019accezione diversa da quella utilizzata dalla teoria marginalista, da Ricardo e da Marx, per i quali esso costituisce un fattore di produzione. Cfr. Lunghini G. (1991), \u201cCapitale\u201d, <em>Enciclopedia delle scienze sociali<\/em>, Volume I, Istituto della Enciclopedia Italiana, Roma.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref19\" name=\"_ftn19\">[19]<\/a> Velthuis O. (2005), <em>Talking Prices: Symbolic Meanings of Prices on the Market for Contemporary Art<\/em>, Princeton University Press, Princeton).<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref20\" name=\"_ftn20\">[20]<\/a> Cfr. Guenzi (2015), \u201cLa teoria della produzione del valore artistico (prima e seconda parte)\u201d, <em>Economia e Diritto<\/em>, nn. 14-15.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref21\" name=\"_ftn21\">[21]<\/a> La teoria degli investimenti del <em>Capital Asset Pricing Model<\/em> (<em>CAPM<\/em>) stabilisce che rendimento atteso e rischio delle attivit\u00e0 finanziarie, ma anche di altro tipo, sono correlati tra di loro linearmente in maniera positiva. Cfr. Sharpe W.F. (1964), &#8220;Capital Asset Prices: a Theory of Market Equilibrium Under Conditions of Risk,&#8221; <em>Journal of Finance<\/em>, vol. 19 n. 3, pp. 425-442 e Fama E. and MacBeth J. (1973), &#8220;Risk, Return and Equilibrium: Empirical Tests,&#8221; <em>Journal of Political Economy<\/em>, vol. 81, 115-146.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref22\" name=\"_ftn22\">[22]<\/a> La possibilit\u00e0 di essere <em>opinion-maker<\/em> \u00e8 pi\u00f9 marcata nel mercato dell\u2019arte, non essendoci una legislazione precisa che vieti i conflitti di interesse. Il mercato inoltre non risulta essere nemmeno disciplinato a livello informativo, vietando ad esempio, come avviene nei mercati finanziari, operazioni di <em>insider-trading<\/em> e aggiotaggio. Infine, non essendo previsto un meccanismo di controllo per il <em>bulk-selling<\/em> di un artista (come ad esempio l\u2019offerta pubblica di vendita), \u00e8 possibile turbare il mercato offrendo grandi quantitativi di opere di un artista, capitalizzando le vendite e facendo irrimediabilmente precipitare le quotazioni in una spirale al ribasso. Famoso \u00e8 il caso del collezionista Charles Saatchi che vendette in blocco la sua collezione relativa alla Transavanguardia Italiana (Thomson D. (2009), <em>Lo squalo da 12 milioni di dollari, La sorprendente economia dell\u2019arte contemporanea<\/em>, Mondadori, Milano). La pratica di disinvestimento nei confronti di un artista, di cui si possiede un ingente quantitativo di opere, in grado quindi di influenzarne il mercato, viene tuttavia in genere portata avanti in maniera graduale e tacita. Ci\u00f2 per una serie di motivi: 1) perch\u00e9 il tempo di dismissione e di reperimento delle controparti \u00e8 normalmente molto lungo 2) per evitare di allarmare subito gli operatori e riuscire a piazzare le opere prima che si inneschi la spirale al ribasso sui prezzi 3) perch\u00e9 sul mercato dell\u2019arte contemporanea allo stato attuale non ci sono strumenti per speculare al ribasso (non esistono derivati n\u00e9 \u00e8 possibile vendere allo scoperto), come invece avviene sui mercati finanziari.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref23\" name=\"_ftn23\">[23]<\/a> Si avr\u00e0 modo di vedere, studiando il segmento <em>High End<\/em>, che in realt\u00e0 solo una piccola parte degli artisti oggi di grande successo verr\u00e0 a lungo andare realmente riconosciuta da un punto di vista culturale e riuscir\u00e0 a rimanere nei libri di storia dell\u2019arte, mentre ci sar\u00e0 la possibilit\u00e0 per altri artisti, rimasti nel dimenticatoio, di riacquisire tardivamente i meriti di cui erano stati ingiustamente privati.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(di Marco Guenzi) Nella precedente disamina del mercato degli artisti affermati (Avant-Garde Market) mancano all\u2019appello alcuni importanti temi, che si intende affrontare nel presente articolo e nel prossimo: ci si <\/p>\n","protected":false},"author":1377,"featured_media":5211,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[10,34,5,1662,1],"tags":[],"class_list":["post-6870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rubriche-economiche","category-economia-dellarte","category-fascicoli","category-numero-di-marzo-2016","category-news"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"es","enabled_languages":["it","en","es"],"languages":{"it":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false},"es":{"title":false,"content":false,"excerpt":false}}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.economiaediritto.it\/wp-content\/uploads\/2014\/05\/1439242_87470475.jpg?fit=3332%2C2278&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9CRXF-1MO","jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.economiaediritto.it\/es\/wp-json\/wp\/v2\/posts\/6870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.economiaediritto.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.economiaediritto.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.economiaediritto.it\/es\/wp-json\/wp\/v2\/users\/1377"}],"replies":[{"embeddable":true,"href":"https:\/\/www.economiaediritto.it\/es\/wp-json\/wp\/v2\/comments?post=6870"}],"version-history":[{"count":2,"href":"https:\/\/www.economiaediritto.it\/es\/wp-json\/wp\/v2\/posts\/6870\/revisions"}],"predecessor-version":[{"id":6874,"href":"https:\/\/www.economiaediritto.it\/es\/wp-json\/wp\/v2\/posts\/6870\/revisions\/6874"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.economiaediritto.it\/es\/wp-json\/wp\/v2\/media\/5211"}],"wp:attachment":[{"href":"https:\/\/www.economiaediritto.it\/es\/wp-json\/wp\/v2\/media?parent=6870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.economiaediritto.it\/es\/wp-json\/wp\/v2\/categories?post=6870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.economiaediritto.it\/es\/wp-json\/wp\/v2\/tags?post=6870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}